{"id":5327,"date":"2024-09-11T09:59:39","date_gmt":"2024-09-11T07:59:39","guid":{"rendered":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/?post_type=tribe_events&#038;p=5327"},"modified":"2024-09-11T09:59:39","modified_gmt":"2024-09-11T07:59:39","slug":"meny-uke-35-4","status":"publish","type":"tribe_events","link":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/hendelse\/meny-uke-35-4\/","title":{"rendered":"Meny uke 35"},"content":{"rendered":"<p>Lunsj: Cottage cheese og yoghurt med t\u00f8rket frukt og puffet havre<\/p>\n<p>Middag: Lapskaus<\/p>\n<p>Kake til kaffemat<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lunsj: Cottage cheese og yoghurt med t\u00f8rket frukt og puffet havre Middag: Lapskaus Kake til kaffemat<\/p>\n","protected":false},"author":9,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[10],"class_list":["post-5327","tribe_events","type-tribe_events","status-publish","tribe_events_cat-10","cat_5"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meny uke 35 - Domkirkehjemmet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/hendelse\/meny-uke-35-4\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meny uke 35 - Domkirkehjemmet\" \/>\n<meta property=\"og:description\" content=\"Lunsj: Cottage cheese og yoghurt med t\u00f8rket frukt og puffet havre Middag: Lapskaus Kake til kaffemat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/hendelse\/meny-uke-35-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Domkirkehjemmet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Ansl. lesetid\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minutt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.haraldsplass.org\\\/domkirkehjemmet\\\/hendelse\\\/meny-uke-35-4\\\/\",\"url\":\"https:\\\/\\\/www.haraldsplass.org\\\/domkirkehjemmet\\\/hendelse\\\/meny-uke-35-4\\\/\",\"name\":\"Meny uke 35 - Domkirkehjemmet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.haraldsplass.org\\\/domkirkehjemmet\\\/#website\"},\"datePublished\":\"2024-09-11T07:59:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.haraldsplass.org\\\/domkirkehjemmet\\\/hendelse\\\/meny-uke-35-4\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.haraldsplass.org\\\/domkirkehjemmet\\\/hendelse\\\/meny-uke-35-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.haraldsplass.org\\\/domkirkehjemmet\\\/hendelse\\\/meny-uke-35-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/www.haraldsplass.org\\\/domkirkehjemmet\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arrangementer\",\"item\":\"https:\\\/\\\/www.haraldsplass.org\\\/domkirkehjemmet\\\/kalender\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Meny uke 35\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.haraldsplass.org\\\/domkirkehjemmet\\\/#website\",\"url\":\"https:\\\/\\\/www.haraldsplass.org\\\/domkirkehjemmet\\\/\",\"name\":\"Domkirkehjemmet\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.haraldsplass.org\\\/domkirkehjemmet\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meny uke 35 - Domkirkehjemmet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/hendelse\/meny-uke-35-4\/","og_locale":"nb_NO","og_type":"article","og_title":"Meny uke 35 - Domkirkehjemmet","og_description":"Lunsj: Cottage cheese og yoghurt med t\u00f8rket frukt og puffet havre Middag: Lapskaus Kake til kaffemat","og_url":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/hendelse\/meny-uke-35-4\/","og_site_name":"Domkirkehjemmet","twitter_card":"summary_large_image","twitter_misc":{"Ansl. lesetid":"1 minutt"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/hendelse\/meny-uke-35-4\/","url":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/hendelse\/meny-uke-35-4\/","name":"Meny uke 35 - Domkirkehjemmet","isPartOf":{"@id":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/#website"},"datePublished":"2024-09-11T07:59:39+00:00","breadcrumb":{"@id":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/hendelse\/meny-uke-35-4\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haraldsplass.org\/domkirkehjemmet\/hendelse\/meny-uke-35-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/hendelse\/meny-uke-35-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/"},{"@type":"ListItem","position":2,"name":"Arrangementer","item":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/kalender\/"},{"@type":"ListItem","position":3,"name":"Meny uke 35"}]},{"@type":"WebSite","@id":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/#website","url":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/","name":"Domkirkehjemmet","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"}]}},"_links":{"self":[{"href":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/wp-json\/wp\/v2\/tribe_events\/5327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":0,"href":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/wp-json\/wp\/v2\/tribe_events\/5327\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/wp-json\/wp\/v2\/media?parent=5327"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/wp-json\/wp\/v2\/tags?post=5327"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.haraldsplass.org\/domkirkehjemmet\/wp-json\/wp\/v2\/tribe_events_cat?post=5327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}